{"id":112,"count":100,"description":"","link":"https:\/\/cms.flipbuilder.com\/tr\/category\/application","name":"ba\u015fvuru","slug":"application","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>application Archives - FlipBuilder<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cms.flipbuilder.com\/tr\/category\/application\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"application Archives - FlipBuilder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cms.flipbuilder.com\/tr\/category\/application\/\" \/>\n<meta property=\"og:site_name\" content=\"FlipBuilder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/cms.flipbuilder.com\/category\/application\",\"url\":\"https:\/\/cms.flipbuilder.com\/category\/application\",\"name\":\"application Archives - FlipBuilder\",\"isPartOf\":{\"@id\":\"https:\/\/cms.flipbuilder.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/cms.flipbuilder.com\/category\/application#breadcrumb\"},\"inLanguage\":\"tr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cms.flipbuilder.com\/category\/application#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cms.flipbuilder.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"application\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cms.flipbuilder.com\/#website\",\"url\":\"https:\/\/cms.flipbuilder.com\/\",\"name\":\"FlipBuilder\",\"description\":\"#1 Flip Book Software\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cms.flipbuilder.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"tr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"application Archives - FlipBuilder","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cms.flipbuilder.com\/tr\/category\/application\/","og_locale":"tr_TR","og_type":"article","og_title":"application Archives - FlipBuilder","og_url":"https:\/\/cms.flipbuilder.com\/tr\/category\/application\/","og_site_name":"FlipBuilder","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cms.flipbuilder.com\/category\/application","url":"https:\/\/cms.flipbuilder.com\/category\/application","name":"uygulama Ar\u015fivleri - FlipBuilder","isPartOf":{"@id":"https:\/\/cms.flipbuilder.com\/#website"},"breadcrumb":{"@id":"https:\/\/cms.flipbuilder.com\/category\/application#breadcrumb"},"inLanguage":"tr"},{"@type":"BreadcrumbList","@id":"https:\/\/cms.flipbuilder.com\/category\/application#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cms.flipbuilder.com\/"},{"@type":"ListItem","position":2,"name":"application"}]},{"@type":"WebSite","@id":"https:\/\/cms.flipbuilder.com\/#website","url":"https:\/\/cms.flipbuilder.com\/","name":"FlipBuilder","description":"#1 Flip Book Yaz\u0131l\u0131m\u0131","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cms.flipbuilder.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"tr"}]}},"_links":{"self":[{"href":"https:\/\/cms.flipbuilder.com\/tr\/wp-json\/wp\/v2\/categories\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms.flipbuilder.com\/tr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cms.flipbuilder.com\/tr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/cms.flipbuilder.com\/tr\/wp-json\/wp\/v2\/posts?categories=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}